{"id":2268,"date":"2021-01-29T14:25:42","date_gmt":"2021-01-29T13:25:42","guid":{"rendered":"http:\/\/www.c2e.fr\/?p=2268"},"modified":"2021-07-15T11:34:11","modified_gmt":"2021-07-15T09:34:11","slug":"bidon-cylindrique-2-joncs-190x260","status":"publish","type":"post","link":"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/","title":{"rendered":"190 x 260 Cylindrical drum with 2 hoops"},"content":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x270-1.jpg'><img width=\"200\" height=\"300\" src=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x270-1-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x270-1-200x300.jpg 200w, https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x270-1-8x12.jpg 8w, https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x270-1.jpg 300w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2268\" class=\"elementor elementor-2268\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bfe31b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bfe31b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3b70e2\" data-id=\"a3b70e2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc3490b elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"cc3490b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Cylindrical drum with 2 hoops \u00f8 190<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e7a6137 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7a6137\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d120bdc\" data-id=\"d120bdc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3999fe animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"e3999fe\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1000\" height=\"1200\" src=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/Bidon-2J-190x260-1.jpg\" class=\"attachment-full size-full wp-image-4152\" alt=\"\" srcset=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/Bidon-2J-190x260-1.jpg 1000w, https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/Bidon-2J-190x260-1-250x300.jpg 250w, https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/Bidon-2J-190x260-1-853x1024.jpg 853w, https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/Bidon-2J-190x260-1-768x922.jpg 768w, https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/Bidon-2J-190x260-1-10x12.jpg 10w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7269a94\" data-id=\"7269a94\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea0a014 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"ea0a014\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Material<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b95b3ed elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b95b3ed\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Tin-plate<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69936ce elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"69936ce\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd59b87 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"fd59b87\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Format<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42f31ff elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"42f31ff\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>190 x 260 mm<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-615f6ad elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"615f6ad\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2132a0 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e2132a0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Type<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1d36f8 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b1d36f8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Welded<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af45cc1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"af45cc1\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95db489 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"95db489\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Interior finish<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8154eae elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"8154eae\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Epoxy coating or plain<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfb9ac6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cfb9ac6\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0747d28 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"0747d28\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Exterior finish<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4036b43 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"4036b43\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>White enamel or plain + offset printing<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ab6f5a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2ab6f5a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1094444 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1094444\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Certification<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d7d0bf elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"8d7d0bf\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>UN II liquid<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69eb838 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"69eb838\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c739411 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"c739411\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Handle<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e2a92e elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"0e2a92e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Plastic or metallic<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cf766f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9cf766f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c57f70 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"8c57f70\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Stackable<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-246ea52 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"246ea52\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Yes<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76931ae elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"76931ae\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f30402 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"0f30402\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Commercial capacity<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5f60d1 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"f5f60d1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>6 L<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99eefe8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"99eefe8\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3098d3e elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3098d3e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>ISO capacity<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fde2a2e elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"fde2a2e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>6,6 L<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2752e1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c2752e1\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ae0de7 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6ae0de7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong>Packaging<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-569f894 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"569f894\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>100 pcs on pallet 800 x 1200<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-449136e elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"449136e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>160 pcs on pallet 1120 x 1420<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51aa66e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51aa66e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b0f3920\" data-id=\"b0f3920\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0829a6 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"e0829a6\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tClosures\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62117dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62117dd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74db9de\" data-id=\"74db9de\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d7a915b elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d7a915b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dc4294e\" data-id=\"dc4294e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e66c87 elementor-widget elementor-widget-image\" data-id=\"6e66c87\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"400\" height=\"227\" src=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/Goulot-a-vis-5690.png\" class=\"attachment-full size-full wp-image-2887\" alt=\"goulot \u00e0 vis pour bidon m\u00e9tallique\" srcset=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/Goulot-a-vis-5690.png 400w, https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/Goulot-a-vis-5690-300x170.png 300w, https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/Goulot-a-vis-5690-16x9.png 16w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9c2b872\" data-id=\"9c2b872\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f361dfb elementor-widget elementor-widget-text-editor\" data-id=\"f361dfb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Screwing plastic spout (\u00f8 42,30 \u2013 56,90)<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2ed7801 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ed7801\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7081850\" data-id=\"7081850\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2db9fc7 elementor-widget elementor-widget-image\" data-id=\"2db9fc7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"400\" height=\"274\" src=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/Flexspout-4230.png\" class=\"attachment-full size-full wp-image-2889\" alt=\"goulot \u00e9tirable pour bidon m\u00e9tallique\" srcset=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/Flexspout-4230.png 400w, https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/Flexspout-4230-300x206.png 300w, https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/Flexspout-4230-16x12.png 16w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-30d17c2\" data-id=\"30d17c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b49359 elementor-widget elementor-widget-text-editor\" data-id=\"2b49359\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Flexspout\u00a0<span style=\"color: var( --e-global-color-secondary );\">(\u00f8 42,30 &#8211; 56,90)<\/span><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fd9893 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2fd9893\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7870786\" data-id=\"7870786\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac6f0ba elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"ac6f0ba\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tTechnical documents\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9664011 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9664011\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b9297e9\" data-id=\"b9297e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8ff590 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a8ff590\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/www.c2e.fr\/fiche-technique\/\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-download\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download the technical sheet<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a750f0d\" data-id=\"a750f0d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb54d62 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"fb54d62\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/04\/Plan-Bidon-o190x260.pdf\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-pencil-ruler\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download the print plan<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9450299 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9450299\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-122031b\" data-id=\"122031b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8cd99e4 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"8cd99e4\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tChoose another height\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb0ed91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb0ed91\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac2ae3f\" data-id=\"ac2ae3f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a940c1 elementor-widget elementor-widget-wpgb-grid\" data-id=\"8a940c1\" data-element_type=\"widget\" data-widget_type=\"wpgb-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- Gridbuilder \u1d42\u1d3e Plugin (https:\/\/wpgridbuilder.com) -->\n<div class=\"wp-grid-builder wpgb-grid-35\" data-options=\"{&quot;id&quot;:35,&quot;type&quot;:&quot;masonry&quot;,&quot;source&quot;:&quot;post_type&quot;,&quot;loader&quot;:0,&quot;layout&quot;:&quot;vertical&quot;,&quot;reveal&quot;:1,&quot;isMainQuery&quot;:false,&quot;lazyLoad&quot;:0,&quot;cardSizes&quot;:{&quot;9999&quot;:{&quot;columns&quot;:6,&quot;height&quot;:240,&quot;gutter&quot;:60,&quot;ratio&quot;:&quot;1.33333&quot;},&quot;1200&quot;:{&quot;columns&quot;:5,&quot;height&quot;:240,&quot;gutter&quot;:20,&quot;ratio&quot;:&quot;1.33333&quot;},&quot;992&quot;:{&quot;columns&quot;:4,&quot;height&quot;:220,&quot;gutter&quot;:20,&quot;ratio&quot;:&quot;1.33333&quot;},&quot;768&quot;:{&quot;columns&quot;:3,&quot;height&quot;:220,&quot;gutter&quot;:20,&quot;ratio&quot;:&quot;1.33333&quot;},&quot;576&quot;:{&quot;columns&quot;:2,&quot;height&quot;:200,&quot;gutter&quot;:20,&quot;ratio&quot;:&quot;1.33333&quot;},&quot;320&quot;:{&quot;columns&quot;:1,&quot;height&quot;:200,&quot;gutter&quot;:20,&quot;ratio&quot;:&quot;1.33333&quot;}},&quot;fitRows&quot;:1,&quot;equalRows&quot;:0,&quot;equalColumns&quot;:1,&quot;fillLastRow&quot;:0,&quot;centerLastRow&quot;:0,&quot;horizontalOrder&quot;:1,&quot;fullWidth&quot;:0,&quot;transitionDelay&quot;:141,&quot;gallerySlideshow&quot;:0,&quot;rowsNumber&quot;:1,&quot;slideAlign&quot;:&quot;left&quot;,&quot;groupCells&quot;:1,&quot;draggable&quot;:1,&quot;initialIndex&quot;:0,&quot;contain&quot;:0,&quot;freeScroll&quot;:0,&quot;freeFriction&quot;:&quot;0.075&quot;,&quot;friction&quot;:&quot;0.285&quot;,&quot;attraction&quot;:&quot;0.025&quot;,&quot;autoPlay&quot;:0,&quot;pageDotAriaLabel&quot;:&quot;Page dot %d&quot;,&quot;isPreview&quot;:false,&quot;isGutenberg&quot;:false,&quot;rightToLeft&quot;:false}\"><div class=\"wpgb-svg-icons\" hidden>\n\t<svg viewbox=\"0 0 120 24\" width=\"0\" height=\"0\">\n\t<defs>\n        <polygon id=\"wpgb-star-svg\" points=\"12 2.5 15.1 8.8 22 9.8 17 14.6 18.2 21.5 12 18.3 5.8 21.5 7 14.6 2 9.8 8.9 8.8\"><\/polygon>\n    <\/defs>\n    <symbol id=\"wpgb-rating-stars-svg\">\n        <use xlink:href=\"#wpgb-star-svg\"><\/use>\n        <use xlink:href=\"#wpgb-star-svg\" x=\"24\"><\/use>\n        <use xlink:href=\"#wpgb-star-svg\" x=\"48\"><\/use>\n        <use xlink:href=\"#wpgb-star-svg\" x=\"72\"><\/use>\n        <use xlink:href=\"#wpgb-star-svg\" x=\"96\"><\/use>\n    <\/symbol>\n<\/svg>\n<\/div>\n<div class=\"wpgb-wrapper\">\n\t<div class=\"wpgb-main\">\n\t<div class=\"wpgb-layout\">\n\t<div class=\"wpgb-viewport\">\n\t\t<div class=\"wpgb-masonry\">\n\t\t\t<article class=\"wpgb-card wpgb-card-6 wpgb-post-2252 wpgb-card-hidden\" data-col=\"1\" data-row=\"1\" data-format=\"standard\"><div class=\"wpgb-card-wrapper\"><div class=\"wpgb-card-inner\" data-action><div class=\"wpgb-card-media wpgb-scheme-light\"><svg data-ratio style=\"padding-top:150%\" viewbox=\"0 0 300 450\"><\/svg><div class=\"wpgb-card-media-thumbnail\"><a href=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-190x235-1.jpg\" tabindex=\"-1\" class=\"wpgb-handle-lb wpgb-lightbox\" data-type=\"image\" data-rel=\"35\" data-title=\"MINI-Bidon-190&#215;235\" title=\"Enlarge photo\"><div style=\"background-image:url(https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-190x235-1.jpg)\"><\/div><noscript><img class=\"wpgb-noscript-img\" src=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-190x235-1.jpg\" alt=\"\" height=\"450\" width=\"300\"><\/noscript><\/a><\/div><\/div><div class=\"wpgb-card-content wpgb-scheme-dark\"><div class=\"wpgb-card-footer\"><h3 class=\"wpgb-block-1 wpgb-idle-scheme-1 wpgb-hover-accent-1\"><a href=\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-190x235\/\">190 x 235 Cylindrical drum<\/a><\/h3><div class=\"wpgb-block-2\">5 L<\/div><\/div><\/div><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-190x235\/\"><\/a><\/div><\/div><\/article><article class=\"wpgb-card wpgb-card-6 wpgb-post-2258 wpgb-card-hidden\" data-col=\"1\" data-row=\"1\" data-format=\"standard\"><div class=\"wpgb-card-wrapper\"><div class=\"wpgb-card-inner\" data-action><div class=\"wpgb-card-media wpgb-scheme-light\"><svg data-ratio style=\"padding-top:150%\" viewbox=\"0 0 300 450\"><\/svg><div class=\"wpgb-card-media-thumbnail\"><a href=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-190x260-1.jpg\" tabindex=\"-1\" class=\"wpgb-handle-lb wpgb-lightbox\" data-type=\"image\" data-rel=\"35\" data-title=\"MINI-Bidon-190&#215;260\" title=\"Enlarge photo\"><div style=\"background-image:url(https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-190x260-1.jpg)\"><\/div><noscript><img class=\"wpgb-noscript-img\" src=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-190x260-1.jpg\" alt=\"\" height=\"450\" width=\"300\"><\/noscript><\/a><\/div><\/div><div class=\"wpgb-card-content wpgb-scheme-dark\"><div class=\"wpgb-card-footer\"><h3 class=\"wpgb-block-1 wpgb-idle-scheme-1 wpgb-hover-accent-1\"><a href=\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-190x260\/\">190 x 260 Cylindrical drum<\/a><\/h3><div class=\"wpgb-block-2\">6 L<\/div><\/div><\/div><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-190x260\/\"><\/a><\/div><\/div><\/article><article class=\"wpgb-card wpgb-card-6 wpgb-post-2264 wpgb-card-hidden\" data-col=\"1\" data-row=\"1\" data-format=\"standard\"><div class=\"wpgb-card-wrapper\"><div class=\"wpgb-card-inner\" data-action><div class=\"wpgb-card-media wpgb-scheme-light\"><svg data-ratio style=\"padding-top:150%\" viewbox=\"0 0 300 450\"><\/svg><div class=\"wpgb-card-media-thumbnail\"><a href=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-190x270-1.jpg\" tabindex=\"-1\" class=\"wpgb-handle-lb wpgb-lightbox\" data-type=\"image\" data-rel=\"35\" data-title=\"MINI-Bidon-190&#215;270\" title=\"Enlarge photo\"><div style=\"background-image:url(https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-190x270-1.jpg)\"><\/div><noscript><img class=\"wpgb-noscript-img\" src=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-190x270-1.jpg\" alt=\"\" height=\"450\" width=\"300\"><\/noscript><\/a><\/div><\/div><div class=\"wpgb-card-content wpgb-scheme-dark\"><div class=\"wpgb-card-footer\"><h3 class=\"wpgb-block-1 wpgb-idle-scheme-1 wpgb-hover-accent-1\"><a href=\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-190x270\/\">190 x 270 Cylindrical drum<\/a><\/h3><div class=\"wpgb-block-2\">6,5 L<\/div><\/div><\/div><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-190x270\/\"><\/a><\/div><\/div><\/article><article class=\"wpgb-card wpgb-card-6 wpgb-post-2267 wpgb-card-hidden\" data-col=\"1\" data-row=\"1\" data-format=\"standard\"><div class=\"wpgb-card-wrapper\"><div class=\"wpgb-card-inner\" data-action><div class=\"wpgb-card-media wpgb-scheme-light\"><svg data-ratio style=\"padding-top:150%\" viewbox=\"0 0 300 450\"><\/svg><div class=\"wpgb-card-media-thumbnail\"><a href=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x235-1.jpg\" tabindex=\"-1\" class=\"wpgb-handle-lb wpgb-lightbox\" data-type=\"image\" data-rel=\"35\" data-title=\"MINI-Bidon-2J-190&#215;235\" title=\"Enlarge photo\"><div style=\"background-image:url(https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x235-1.jpg)\"><\/div><noscript><img class=\"wpgb-noscript-img\" src=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x235-1.jpg\" alt=\"\" height=\"450\" width=\"300\"><\/noscript><\/a><\/div><\/div><div class=\"wpgb-card-content wpgb-scheme-dark\"><div class=\"wpgb-card-footer\"><h3 class=\"wpgb-block-1 wpgb-idle-scheme-1 wpgb-hover-accent-1\"><a href=\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x235\/\">190 x 235 Cylindrical drum with 2 hoops<\/a><\/h3><div class=\"wpgb-block-2\">5 L<\/div><\/div><\/div><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x235\/\"><\/a><\/div><\/div><\/article><article class=\"wpgb-card wpgb-card-6 wpgb-post-2268 wpgb-card-hidden\" data-col=\"1\" data-row=\"1\" data-format=\"standard\"><div class=\"wpgb-card-wrapper\"><div class=\"wpgb-card-inner\" data-action><div class=\"wpgb-card-media wpgb-scheme-light\"><svg data-ratio style=\"padding-top:150%\" viewbox=\"0 0 300 450\"><\/svg><div class=\"wpgb-card-media-thumbnail\"><a href=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x260-1.jpg\" tabindex=\"-1\" class=\"wpgb-handle-lb wpgb-lightbox\" data-type=\"image\" data-rel=\"35\" data-title=\"MINI-Bidon-2J-190&#215;260\" title=\"Enlarge photo\"><div style=\"background-image:url(https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x260-1.jpg)\"><\/div><noscript><img class=\"wpgb-noscript-img\" src=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x260-1.jpg\" alt=\"\" height=\"450\" width=\"300\"><\/noscript><\/a><\/div><\/div><div class=\"wpgb-card-content wpgb-scheme-dark\"><div class=\"wpgb-card-footer\"><h3 class=\"wpgb-block-1 wpgb-idle-scheme-1 wpgb-hover-accent-1\"><a href=\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/\">190 x 260 Cylindrical drum with 2 hoops<\/a><\/h3><div class=\"wpgb-block-2\">6 L<\/div><\/div><\/div><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/\"><\/a><\/div><\/div><\/article><article class=\"wpgb-card wpgb-card-6 wpgb-post-2269 wpgb-card-hidden\" data-col=\"1\" data-row=\"1\" data-format=\"standard\"><div class=\"wpgb-card-wrapper\"><div class=\"wpgb-card-inner\" data-action><div class=\"wpgb-card-media wpgb-scheme-light\"><svg data-ratio style=\"padding-top:150%\" viewbox=\"0 0 300 450\"><\/svg><div class=\"wpgb-card-media-thumbnail\"><a href=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x270-1.jpg\" tabindex=\"-1\" class=\"wpgb-handle-lb wpgb-lightbox\" data-type=\"image\" data-rel=\"35\" data-title=\"MINI-Bidon-2J-190&#215;270\" title=\"Enlarge photo\"><div style=\"background-image:url(https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x270-1.jpg)\"><\/div><noscript><img class=\"wpgb-noscript-img\" src=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x270-1.jpg\" alt=\"\" height=\"450\" width=\"300\"><\/noscript><\/a><\/div><\/div><div class=\"wpgb-card-content wpgb-scheme-dark\"><div class=\"wpgb-card-footer\"><h3 class=\"wpgb-block-1 wpgb-idle-scheme-1 wpgb-hover-accent-1\"><a href=\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x270\/\">190 x 270 Cylindrical drum with 2 hoops<\/a><\/h3><div class=\"wpgb-block-2\">6,5 L<\/div><\/div><\/div><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x270\/\"><\/a><\/div><\/div><\/article>\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div class=\"wpgb-area wpgb-area-bottom-1\">\n\t<button type=\"button\" class=\"wpgb-prev-button\" aria-label=\"Previous slide\" hidden>\n\t<svg><use xlink:href=\"https:\/\/www.c2e.fr\/wp-content\/plugins\/wp-grid-builder\/frontend\/assets\/svg\/arrows\/arrow-left.svg#wpgb-icon\"\/><\/svg><\/button>\n<ol class=\"wpgb-page-dots\"><\/ol>\n<button type=\"button\" class=\"wpgb-next-button\" aria-label=\"Next slide\" hidden>\n\t<svg><use xlink:href=\"https:\/\/www.c2e.fr\/wp-content\/plugins\/wp-grid-builder\/frontend\/assets\/svg\/arrows\/arrow-right.svg#wpgb-icon\"\/><\/svg><\/button>\n<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d39c243 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d39c243\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e4d1641\" data-id=\"e4d1641\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2aa883f elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"2aa883f\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-recycle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ceeb41 elementor-widget elementor-widget-text-editor\" data-id=\"3ceeb41\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Recyclable steel<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Bidon cylindrique 2 joncs \u00f8 190 Mat\u00e9riau Fer blanc Format 190 x 260 mm Type Soud\u00e9 Finition int\u00e9rieur Vernis ou nu Finition ext\u00e9rieur Couch\u00e9 blanc ou nu + impression offset Homologation UN II liquide Poign\u00e9e Plastique ou m\u00e9tallique Gerbable Oui Capacit\u00e9 commerciale 6 L Capacit\u00e9 ISO 6,6 L Conditionnement 100 pcs sur palette 800 x&#8230;<\/p>","protected":false},"author":2,"featured_media":4146,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"categories":[1],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bidon cylindrique 2 joncs 190 x 260 - Compagnie Europ\u00e9enne d&#039;Emballage<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bidon cylindrique 2 joncs 190 x 260 - Compagnie Europ\u00e9enne d&#039;Emballage\" \/>\n<meta property=\"og:description\" content=\"Bidon cylindrique 2 joncs \u00f8 190 Mat\u00e9riau Fer blanc Format 190 x 260 mm Type Soud\u00e9 Finition int\u00e9rieur Vernis ou nu Finition ext\u00e9rieur Couch\u00e9 blanc ou nu + impression offset Homologation UN II liquide Poign\u00e9e Plastique ou m\u00e9tallique Gerbable Oui Capacit\u00e9 commerciale 6 L Capacit\u00e9 ISO 6,6 L Conditionnement 100 pcs sur palette 800 x...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/\" \/>\n<meta property=\"og:site_name\" content=\"Compagnie Europ\u00e9enne d&#039;Emballage\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-29T13:25:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-15T09:34:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x260-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dominique BIRAY\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dominique BIRAY\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.c2e.fr\/#organization\",\"name\":\"Compagnie Europ\u00e9enne d'Emballages\",\"url\":\"https:\/\/www.c2e.fr\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.c2e.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2020\/12\/Logo-C2E.png\",\"contentUrl\":\"https:\/\/www.c2e.fr\/wp-content\/uploads\/2020\/12\/Logo-C2E.png\",\"width\":300,\"height\":245,\"caption\":\"Compagnie Europ\u00e9enne d'Emballages\"},\"image\":{\"@id\":\"https:\/\/www.c2e.fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.c2e.fr\/#website\",\"url\":\"https:\/\/www.c2e.fr\/\",\"name\":\"Compagnie Europ\u00e9enne Emballages\",\"description\":\"Fabricant d&#039;emballages m\u00e9talliques\",\"publisher\":{\"@id\":\"https:\/\/www.c2e.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.c2e.fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/\",\"url\":\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/\",\"name\":\"Bidon cylindrique 2 joncs 190 x 260 - Compagnie Europ\u00e9enne d&#039;Emballage\",\"isPartOf\":{\"@id\":\"https:\/\/www.c2e.fr\/#website\"},\"datePublished\":\"2021-01-29T13:25:42+00:00\",\"dateModified\":\"2021-07-15T09:34:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.c2e.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bidon cylindrique 2 joncs 190 x 260\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/\"},\"author\":{\"name\":\"Dominique BIRAY\",\"@id\":\"https:\/\/www.c2e.fr\/#\/schema\/person\/ec1c0a841fc82bfc4dd28178a2d7601b\"},\"headline\":\"Bidon cylindrique 2 joncs 190 x 260\",\"datePublished\":\"2021-01-29T13:25:42+00:00\",\"dateModified\":\"2021-07-15T09:34:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/\"},\"wordCount\":112,\"publisher\":{\"@id\":\"https:\/\/www.c2e.fr\/#organization\"},\"articleSection\":[\"Non class\u00e9\"],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.c2e.fr\/#\/schema\/person\/ec1c0a841fc82bfc4dd28178a2d7601b\",\"name\":\"Dominique BIRAY\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.c2e.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f5c79dbacafc6e215084300621cafadb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f5c79dbacafc6e215084300621cafadb?s=96&d=mm&r=g\",\"caption\":\"Dominique BIRAY\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bidon cylindrique 2 joncs 190 x 260 - Compagnie Europ\u00e9enne d&#039;Emballage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/","og_locale":"en_US","og_type":"article","og_title":"Bidon cylindrique 2 joncs 190 x 260 - Compagnie Europ\u00e9enne d&#039;Emballage","og_description":"Bidon cylindrique 2 joncs \u00f8 190 Mat\u00e9riau Fer blanc Format 190 x 260 mm Type Soud\u00e9 Finition int\u00e9rieur Vernis ou nu Finition ext\u00e9rieur Couch\u00e9 blanc ou nu + impression offset Homologation UN II liquide Poign\u00e9e Plastique ou m\u00e9tallique Gerbable Oui Capacit\u00e9 commerciale 6 L Capacit\u00e9 ISO 6,6 L Conditionnement 100 pcs sur palette 800 x...","og_url":"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/","og_site_name":"Compagnie Europ\u00e9enne d&#039;Emballage","article_published_time":"2021-01-29T13:25:42+00:00","article_modified_time":"2021-07-15T09:34:11+00:00","og_image":[{"width":300,"height":450,"url":"https:\/\/www.c2e.fr\/wp-content\/uploads\/2021\/03\/MINI-Bidon-2J-190x260-1.jpg","type":"image\/jpeg"}],"author":"Dominique BIRAY","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dominique BIRAY","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.c2e.fr\/#organization","name":"Compagnie Europ\u00e9enne d'Emballages","url":"https:\/\/www.c2e.fr\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.c2e.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.c2e.fr\/wp-content\/uploads\/2020\/12\/Logo-C2E.png","contentUrl":"https:\/\/www.c2e.fr\/wp-content\/uploads\/2020\/12\/Logo-C2E.png","width":300,"height":245,"caption":"Compagnie Europ\u00e9enne d'Emballages"},"image":{"@id":"https:\/\/www.c2e.fr\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/www.c2e.fr\/#website","url":"https:\/\/www.c2e.fr\/","name":"Compagnie Europ\u00e9enne Emballages","description":"Fabricant d&#039;emballages m\u00e9talliques","publisher":{"@id":"https:\/\/www.c2e.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.c2e.fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/","url":"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/","name":"Bidon cylindrique 2 joncs 190 x 260 - Compagnie Europ\u00e9enne d&#039;Emballage","isPartOf":{"@id":"https:\/\/www.c2e.fr\/#website"},"datePublished":"2021-01-29T13:25:42+00:00","dateModified":"2021-07-15T09:34:11+00:00","breadcrumb":{"@id":"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.c2e.fr\/"},{"@type":"ListItem","position":2,"name":"Bidon cylindrique 2 joncs 190 x 260"}]},{"@type":"Article","@id":"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/#article","isPartOf":{"@id":"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/"},"author":{"name":"Dominique BIRAY","@id":"https:\/\/www.c2e.fr\/#\/schema\/person\/ec1c0a841fc82bfc4dd28178a2d7601b"},"headline":"Bidon cylindrique 2 joncs 190 x 260","datePublished":"2021-01-29T13:25:42+00:00","dateModified":"2021-07-15T09:34:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.c2e.fr\/en\/bidon-cylindrique-2-joncs-190x260\/"},"wordCount":112,"publisher":{"@id":"https:\/\/www.c2e.fr\/#organization"},"articleSection":["Non class\u00e9"],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.c2e.fr\/#\/schema\/person\/ec1c0a841fc82bfc4dd28178a2d7601b","name":"Dominique BIRAY","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.c2e.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f5c79dbacafc6e215084300621cafadb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5c79dbacafc6e215084300621cafadb?s=96&d=mm&r=g","caption":"Dominique BIRAY"}}]}},"_links":{"self":[{"href":"https:\/\/www.c2e.fr\/en\/wp-json\/wp\/v2\/posts\/2268"}],"collection":[{"href":"https:\/\/www.c2e.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.c2e.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.c2e.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.c2e.fr\/en\/wp-json\/wp\/v2\/comments?post=2268"}],"version-history":[{"count":18,"href":"https:\/\/www.c2e.fr\/en\/wp-json\/wp\/v2\/posts\/2268\/revisions"}],"predecessor-version":[{"id":7090,"href":"https:\/\/www.c2e.fr\/en\/wp-json\/wp\/v2\/posts\/2268\/revisions\/7090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.c2e.fr\/en\/wp-json\/wp\/v2\/media\/4146"}],"wp:attachment":[{"href":"https:\/\/www.c2e.fr\/en\/wp-json\/wp\/v2\/media?parent=2268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.c2e.fr\/en\/wp-json\/wp\/v2\/categories?post=2268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.c2e.fr\/en\/wp-json\/wp\/v2\/tags?post=2268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}